{"id":25747,"date":"2022-02-15T19:03:07","date_gmt":"2022-02-15T19:03:07","guid":{"rendered":"https:\/\/www.sheffieldhaworth.com\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/"},"modified":"2025-08-04T17:30:12","modified_gmt":"2025-08-04T16:30:12","slug":"que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion","status":"publish","type":"post","link":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/","title":{"rendered":"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n?"},"content":{"rendered":"\n<p><strong>Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.<\/strong><\/p>\n\n<p>Hay mucha confusi\u00f3n sobre los marcos de competencias conductuales en el mundo de la contrataci\u00f3n de talento directivo. Las organizaciones e incluso los consultores de selecci\u00f3n de personal no comprenden su valor o carecen de la formaci\u00f3n o la experiencia necesarias para utilizarlos en todo su potencial. Esto es un problema, porque puede hacer que las organizaciones pierdan el nivel adicional de validaci\u00f3n que aportan a la hora de contratar talentos senior.  <\/p>\n\n<p>Este art\u00edculo pretende aclarar qu\u00e9 son los marcos de competencias conductuales en el contexto de la evaluaci\u00f3n, sus ventajas potenciales para la selecci\u00f3n y contrataci\u00f3n de talentos directivos, y c\u00f3mo aplicarlos eficazmente.<\/p>\n\n<p>He aqu\u00ed un ejemplo de c\u00f3mo el uso de marcos de competencias puede ayudar en la selecci\u00f3n de candidatos. En 2021, un cliente ten\u00eda una reserva sobre uno de los dos candidatos para un puesto importante. Este candidato, padre de familia, hab\u00eda pedido flexibilidad en el horario laboral. Al cliente le preocupaba que esto significara que el candidato podr\u00eda no ser ambicioso o dedicado al puesto, lo que implicaba que podr\u00eda priorizar la vida familiar sobre el trabajo.   <\/p>\n\n<p>Evaluamos al candidato seg\u00fan el marco de competencias de comportamiento acordado con el cliente. El perfil resultante de la evaluaci\u00f3n mostr\u00f3 que el candidato era extremadamente ambicioso y organizado. Tambi\u00e9n revel\u00f3 que hab\u00eda pedido flexibilidad porque le ayudar\u00eda a trabajar de forma m\u00e1s productiva y a aumentar la productividad de su equipo. Tras presentar estos resultados al cliente, se sinti\u00f3 c\u00f3modo ofreci\u00e9ndole el puesto.     <\/p>\n\n<p><strong>\u00bfQu\u00e9 es un marco de competencias conductuales?<\/strong><\/p>\n\n<p>Una de las razones por las que persiste la confusi\u00f3n en torno a los marcos de competencias conductuales es que muchos de nosotros hemos sido condicionados a ver la \u00abcompetencia\u00bb o las \u00abcompetencias\u00bb casi exclusivamente en t\u00e9rminos de capacidades t\u00e9cnicas. En el contexto de la contrataci\u00f3n, la capacidad t\u00e9cnica prevalece a la hora de evaluar la idoneidad de un candidato para un determinado puesto. <\/p>\n\n<p>Demostrar la competencia t\u00e9cnica es enormemente importante, pero a menudo durante la selecci\u00f3n de candidatos se utiliza excluyendo otros factores. Como resultado, las competencias de comportamiento se descuidan o ni siquiera se tienen en cuenta. Muchos consultores de contrataci\u00f3n nunca las han utilizado.  <\/p>\n\n<p>En su forma m\u00e1s simple, un marco de competencias de comportamiento define los comportamientos y actitudes visibles necesarios para desempe\u00f1ar la funci\u00f3n, en lugar de los conocimientos t\u00e9cnicos requeridos. En otras palabras, mientras que la descripci\u00f3n de un puesto dice \u00abqu\u00e9\u00bb tienes que saber para hacer el trabajo (es decir, los conocimientos t\u00e9cnicos), las competencias describen \u00abc\u00f3mo\u00bb deber\u00eda hacerse idealmente el trabajo. <\/p>\n\n<p>Las competencias de comportamiento abarcan aspectos como la resoluci\u00f3n de problemas, la toma de decisiones, el liderazgo del pensamiento, la comunicaci\u00f3n, la orientaci\u00f3n al cliente, etc. Si nos fijamos en el ejemplo de un alto ejecutivo, suele ser importante que muestre la capacidad de ser un l\u00edder estrat\u00e9gico, de impulsar y aportar valor a la empresa, que pueda promover y buscar mejoras en los procesos, que pueda preparar para el futuro la capacidad de su equipo, etc. <\/p>\n\n<p>Aqu\u00ed tienes una representaci\u00f3n visual del marco de competencias de comportamiento de un alto dirigente, con los ep\u00edgrafes de las competencias de comportamiento en azul:<\/p>\n\r\n<div class=\"d-block text-left\">\r\n\r\n\t<img decoding=\"async\" class=\"responsive-image\" style=\"border-radius: 0px;max-width: 300px\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/02\/Picture1.png\" alt=\"\" \/>\r\n\r\n<\/div>\r\n\t\t                \n<p>Al igual que con las competencias t\u00e9cnicas, colaboramos con los clientes para elaborar un marco basado en las exigencias de la empresa, los retos operativos internos, las tendencias del mercado, etc. El gr\u00e1fico anterior muestra algunos de los factores externos clave que influyen en las competencias deseadas alrededor del exterior de la rueda. En este caso, los factores incluyen el aumento de la diversidad de las partes interesadas, la mayor complejidad de los retos empresariales y los modelos de negocio, la mayor atenci\u00f3n a la seguridad psicol\u00f3gica y el bienestar de los miembros del equipo, etc.  <\/p>\n\n<p>A partir de este ejemplo, puedes ver que las competencias variar\u00e1n en funci\u00f3n de los factores que influyan, de modo que los marcos de competencias comportamentales tambi\u00e9n pueden adaptarse a las especificidades de un cliente determinado, as\u00ed como al contexto empresarial, siempre cambiante pero imperante. A veces, las empresas ya tienen sus propios marcos de competencias comportamentales derivados de su visi\u00f3n y sus valores. En ese caso, utilizar\u00edamos ese marco para la evaluaci\u00f3n, aunque sigue siendo mucho m\u00e1s habitual que nos pidan que dise\u00f1emos marcos para funciones espec\u00edficas.  <\/p>\n\n<p><strong>Por qu\u00e9 son importantes los marcos de competencias conductuales<\/strong><\/p>\n\n<p>Evaluar a las personas y a los equipos en funci\u00f3n de marcos de competencias comportamentales tiene muchas ventajas potenciales. Estos marcos son un medio para medir el rendimiento individual en toda la empresa de forma transparente y coherente. Esto permite mantener conversaciones en profundidad sobre el rendimiento y el desarrollo a lo largo del ciclo de vida del empleado. Tambi\u00e9n pueden ayudar a planificar el desarrollo profesional a nivel individual y empresarial.   <\/p>\n\n<p>Los marcos de competencias comportamentales aclaran el v\u00ednculo entre el papel del individuo y su organizaci\u00f3n, aumentando la apropiaci\u00f3n personal de las metas y objetivos empresariales. Tambi\u00e9n pueden desempe\u00f1ar un papel importante a la hora de atraer y retener al personal, y pueden utilizarse para apuntalar el reclutamiento y la selecci\u00f3n, como ya hemos visto. En el contexto de la selecci\u00f3n, aportan estructura, coherencia y pueden mitigar el sesgo al proporcionar criterios de selecci\u00f3n claramente definidos y transparentes en las distintas partes del proceso de evaluaci\u00f3n.    <\/p>\n\n<p><strong>C\u00f3mo utilizar eficazmente los marcos de competencias conductuales<\/strong><\/p>\n\n<p>Cuando se utilizan marcos de competencias comportamentales para el reclutamiento y la selecci\u00f3n, es importante utilizarlos bien para sacarles el m\u00e1ximo partido. Esto significa que, como organizaci\u00f3n, tienes que tener claro qu\u00e9 comportamientos y actitudes requiere un determinado puesto. Como hemos visto, podr\u00edas empezar por elegir comportamientos que sean coherentes con tu visi\u00f3n y valores organizativos y los sustenten.  <\/p>\n\n<p>Sin embargo, tambi\u00e9n es importante fijarse en los factores y tendencias externos del mercado que puedan influir en los comportamientos de \u00e9xito. Por ejemplo, el Director Financiero de \u00e9xito de hoy en d\u00eda a menudo tiene que ser capaz de pensar estrat\u00e9gicamente, dar prioridad a los objetivos empresariales fuera de Finanzas y mostrar preocupaci\u00f3n por el bienestar mental de su equipo. <\/p>\n\n<p>Piensa tambi\u00e9n en las prioridades y retos de tu empresa. \u00bfQu\u00e9 comportamientos muestran otros altos dirigentes de \u00e9xito que puedan aplicarse tambi\u00e9n al puesto que quieres desempe\u00f1ar? Tambi\u00e9n puede ser \u00fatil pensar en los comportamientos que no quieres ver.  <\/p>\n\n<p>Una parte fundamental del proceso de evaluaci\u00f3n consiste en comparar nuestros resultados de los datos psicom\u00e9tricos con las competencias de comportamiento. A continuaci\u00f3n, realizamos una entrevista de validaci\u00f3n con el candidato, que es cuando esencialmente contrastamos la hip\u00f3tesis de los datos con el marco de competencias. Despu\u00e9s, elaboramos un informe con nuestros resultados antes de informar al cliente. Una vez tomada la decisi\u00f3n de selecci\u00f3n, tambi\u00e9n proporcionamos informaci\u00f3n al candidato sobre sus resultados.   <\/p>\n\n<p>Como hemos visto, a menudo la evaluaci\u00f3n de las competencias de comportamiento proporciona un nivel adicional de validaci\u00f3n para los candidatos que pueden parecer ideales sobre el papel, pero que luego muestran muy pocos de los comportamientos que has identificado como necesarios para el \u00e9xito. Por otra parte, un buen marco de competencias tambi\u00e9n puede ayudar a elegir entre dos o tres candidatos que han dado una buena imagen en las entrevistas y que tienen excelentes competencias t\u00e9cnicas y una experiencia impresionante. <\/p>\n\n<p>We hope this article has helped to clear up some of the confusion around behavioural competency frameworks and their usefulness. If you have any questions or queries, feel free to get in touch at <a href=\"mailto:shleadership@sheffieldhaworth.com\">shleadership@sheffieldhaworth.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[430,392,363],"tags":[],"class_list":["post-25747","post","type-post","status-publish","format-standard","hentry","category-asesoria-de-liderazgo","category-liderazgo","category-perspectivas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth<\/title>\n<meta name=\"description\" content=\"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth\" \/>\n<meta property=\"og:description\" content=\"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/\" \/>\n<meta property=\"og:site_name\" content=\"Sheffield Haworth\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-15T19:03:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T16:30:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/sh-default-social-card.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emberton92f71\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emberton92f71\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/\"},\"author\":{\"name\":\"emberton92f71\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\"},\"headline\":\"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n?\",\"datePublished\":\"2022-02-15T19:03:07+00:00\",\"dateModified\":\"2025-08-04T16:30:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/\"},\"wordCount\":1372,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\"},\"articleSection\":[\"Asesor\u00eda de Liderazgo\",\"Liderazgo\",\"Perspectivas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/\",\"name\":\"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#website\"},\"datePublished\":\"2022-02-15T19:03:07+00:00\",\"dateModified\":\"2025-08-04T16:30:12+00:00\",\"description\":\"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/\",\"name\":\"Sheffield Haworth\",\"description\":\"Helping organisations and individuals to reach their potential\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\",\"name\":\"Sheffield Haworth\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"width\":311,\"height\":151,\"caption\":\"Sheffield Haworth\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sheffield-haworth\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\",\"name\":\"emberton92f71\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"caption\":\"emberton92f71\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth","description":"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth","og_description":"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.","og_url":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/","og_site_name":"Sheffield Haworth","article_published_time":"2022-02-15T19:03:07+00:00","article_modified_time":"2025-08-04T16:30:12+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/sh-default-social-card.jpg","type":"image\/jpeg"}],"author":"emberton92f71","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emberton92f71","Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/#article","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/"},"author":{"name":"emberton92f71","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0"},"headline":"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n?","datePublished":"2022-02-15T19:03:07+00:00","dateModified":"2025-08-04T16:30:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/"},"wordCount":1372,"publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization"},"articleSection":["Asesor\u00eda de Liderazgo","Liderazgo","Perspectivas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/","url":"https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/","name":"\u00bfQu\u00e9 es un marco de competencias conductuales en el contexto de la evaluaci\u00f3n? - Sheffield Haworth","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#website"},"datePublished":"2022-02-15T19:03:07+00:00","dateModified":"2025-08-04T16:30:12+00:00","description":"Cuando se trata de contrataci\u00f3n y selecci\u00f3n o de desarrollo profesional, es importante tener en cuenta algo m\u00e1s que las competencias t\u00e9cnicas.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sheffieldhaworth.com\/es\/que-es-un-marco-de-competencias-conductuales-en-el-contexto-de-la-evaluacion\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#website","url":"https:\/\/www.sheffieldhaworth.com\/es\/","name":"Sheffield Haworth","description":"Helping organisations and individuals to reach their potential","publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sheffieldhaworth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization","name":"Sheffield Haworth","url":"https:\/\/www.sheffieldhaworth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","width":311,"height":151,"caption":"Sheffield Haworth"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/sheffield-haworth\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0","name":"emberton92f71","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","caption":"emberton92f71"}}]}},"_links":{"self":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts\/25747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/comments?post=25747"}],"version-history":[{"count":0,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts\/25747\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/media?parent=25747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/categories?post=25747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/tags?post=25747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}