{"id":25645,"date":"2021-10-27T12:20:46","date_gmt":"2021-10-27T11:20:46","guid":{"rendered":"https:\/\/www.sheffieldhaworth.com\/comprender-el-valor-del-seguimiento\/"},"modified":"2025-08-04T17:29:29","modified_gmt":"2025-08-04T16:29:29","slug":"comprender-el-valor-del-seguimiento","status":"publish","type":"post","link":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/","title":{"rendered":"Comprender el valor del seguimiento"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">El mundo empresarial est\u00e1 obsesionado con el liderazgo, pero el \u00abseguimiento\u00bb es igual de importante, si no m\u00e1s. Busca en Google el t\u00e9rmino \u00abliderazgo\u00bb o busca libros sobre el tema en Amazon, y obtendr\u00e1s decenas de miles de resultados. Intenta hacer lo mismo con \u00abseguimiento\u00bb: te costar\u00e1 encontrar muchos libros o art\u00edculos sobre el tema.  <\/p>\n\n<p class=\"wp-block-paragraph\">Nadie va a Harvard para aprender a seguir. Tampoco encontrar\u00e1s muchos cursos que ensalcen sus virtudes. Sin embargo, saber c\u00f3mo ser un buen seguidor es vital para hacer las cosas. Como l\u00edder, no s\u00f3lo tienes que saber c\u00f3mo fomentar comportamientos positivos de seguimiento en tu equipo, sino que a menudo t\u00fa mismo tienes que ser un seguidor eficaz.   <\/p>\n\n<p class=\"wp-block-paragraph\">Tomemos el ejemplo de la Real Academia Militar de Sandhurst. Es el centro de excelencia de liderazgo del ej\u00e9rcito brit\u00e1nico. La capilla de la academia es, en muchos sentidos, el hogar espiritual del liderazgo militar en Gran Breta\u00f1a. Sin embargo, cuando sales de la capilla, te enfrentas a un monumento conmemorativo de todos los dem\u00e1s rangos de soldados brit\u00e1nicos que cayeron -y siguen cayendo- en diversos conflictos. Es un duro recordatorio para los futuros l\u00edderes en formaci\u00f3n del ej\u00e9rcito de que sin todos esos seguidores que realizan un trabajo brillante en pos de la consecuci\u00f3n de la misi\u00f3n , no puedes ser un l\u00edder.    <\/p>\n\n<p class=\"wp-block-paragraph\">De hecho, todas las ramas del ej\u00e9rcito brit\u00e1nico -y desde luego el ej\u00e9rcito y los marines, en los que tus autores sirvieron en el pasado- inculcan la idea de que tus seguidores te convierten en l\u00edder. Que no puedes ser un l\u00edder eficaz sin seguidores eficaces. Comprender que el papel de un oficial es servir a tus tropas es la base de la forma en que los militares ense\u00f1an y practican el liderazgo.  <\/p>\n\n<p class=\"wp-block-paragraph\">Ahora, aplica este concepto al liderazgo en la empresa. Puede que todos busquemos el liderazgo, pero en realidad es el seguimiento lo que domina nuestra vida laboral. Incluso como l\u00edderes, seguimos tan a menudo -si no m\u00e1s- de lo que lideramos.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 es el seguimiento y por qu\u00e9 es importante?<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Es \u00fatil definir lo que entendemos por liderazgo. En pocas palabras, es la capacidad de aceptar bien una direcci\u00f3n, de alinearse detr\u00e1s de un programa o proyecto, de formar parte de un equipo y de cumplir lo que se espera de ti. <\/p>\n\n<p class=\"wp-block-paragraph\">Su importancia deber\u00eda ser bastante obvia. Sin la capacidad de asumir la direcci\u00f3n y cumplir un proyecto, ese proyecto fracasar\u00e1. Sin embargo, lo que es a\u00fan m\u00e1s importante que las habilidades obvias requeridas es la mentalidad y el comportamiento.  <\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Seguimiento eficaz frente a seguimiento ineficaz<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">De hecho, la capacidad de cambiar de papel, de cambiar de prioridades, de ofrecer apoyo, podr\u00eda decirse que define el seguimiento eficaz. Esto es lo que hacen las personas de los equipos de alto rendimiento: suelen ser capaces de cambiar de papel con mucha facilidad. <\/p>\n\n<p class=\"wp-block-paragraph\">A pesar de que el seguimiento nunca ha recibido la misma atenci\u00f3n que el liderazgo, la diferencia entre los comportamientos de seguimiento eficaces e ineficaces se codific\u00f3 ya en 1988, en un art\u00edculo seminal sobre el tema publicado en la Harvard Business Review <a href=\"https:\/\/hbr.org\/1988\/11\/in-praise-of-followers\">por Robert Kelley<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">En este art\u00edculo, Kelley establece la diferencia entre los comportamientos de seguimiento eficaces e ineficaces de la siguiente manera:<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Comportamientos de seguimiento ineficaces<\/strong><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">A menudo esto se traduce en miembros del equipo sentados esperando a que les digan lo que tienen que hacer, neg\u00e1ndose a tomar la iniciativa.<\/p>\n\n<p class=\"wp-block-paragraph\">Yendo un paso m\u00e1s all\u00e1, podr\u00eda manifestarse como lo que Kelley llama comportamiento \u00absuperviviente\u00bb, que es cuando eres perfectamente capaz y tienes un buen cerebro, pero has elegido desconectarte para pasar el d\u00eda y hacer lo m\u00ednimo.<\/p>\n\n<p class=\"wp-block-paragraph\">Quiz\u00e1 el peor de los comportamientos ineficaces sea cuando est\u00e1s enfadado y te quejas vocalmente, sin importarte qui\u00e9n sepa c\u00f3mo te sientes. Este comportamiento puede volverse subversivo y empezar a sembrar la discordia. <\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Comportamientos eficaces de seguimiento<\/strong><\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Los comportamientos eficaces, por el contrario, incluyen:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>La capacidad de pensar por s\u00ed mismos<\/li>\n\n\n\n<li>Pedir perd\u00f3n, no permiso<\/li>\n\n\n\n<li>Disposici\u00f3n a asumir cierto grado de riesgo<\/li>\n\n\n\n<li>Capacidad de utilizar su propio criterio<\/li>\n\n\n\n<li>Sentirse c\u00f3modo levantando la mano y diciendo cuando no saben algo<\/li>\n\n\n\n<li>Ser capaz de operar de forma independiente<\/li>\n\n\n\n<li>Hambre de ampliar su nivel de competencia<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Este \u00faltimo punto es importante, porque los seguidores eficaces suelen esforzarse por aumentar su competencia, por esforzarse, aprender m\u00e1s y desarrollarse pidiendo tareas m\u00e1s exigentes o mentores.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo creamos una cultura en la que prospere un comportamiento de seguimiento eficaz en un mundo laboral h\u00edbrido?<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">El liderazgo desempe\u00f1a un papel clave en el fomento de un seguimiento eficaz. Si creas las condiciones para que prospere el seguimiento eficaz, a trav\u00e9s de tu liderazgo, entonces prosperar\u00e1. Si creas las condiciones para la alienaci\u00f3n o la supervivencia, entonces esos comportamientos prosperar\u00e1n. De ti depende lo que crees.   <\/p>\n\n<p class=\"wp-block-paragraph\">Con el auge de las nuevas formas de trabajo -en particular el trabajo h\u00edbrido-, tu liderazgo desempe\u00f1a un papel m\u00e1s importante que nunca. Las personas pueden elegir cu\u00e1nto trabajar. Pueden elegir a qu\u00e9 dedican su tiempo y a qu\u00e9 dan prioridad.  <\/p>\n\n<p class=\"wp-block-paragraph\">El esfuerzo discrecional es, en \u00faltima instancia, de lo que se trata. Tus seguidores eficaces se sienten muy c\u00f3modos proporcion\u00e1ndote esfuerzo discrecional. Tambi\u00e9n se sienten muy c\u00f3modos d\u00e1ndose la vuelta y dici\u00e9ndote cu\u00e1ndo est\u00e1n al l\u00edmite o en peligro de agotarse. Puedes confiar en ellos en este contexto, porque tienen un buen historial de ser personas honestas, dignas de confianza y fiables que te dicen la verdad. Si dicen que est\u00e1n al m\u00e1ximo, lo m\u00e1s probable es que lo est\u00e9n.    <\/p>\n\n<p class=\"wp-block-paragraph\">Por supuesto, si te preocupas por el miembro de tu equipo, ser\u00e1s receptivo a las se\u00f1ales de exceso de trabajo y posible agotamiento. Si observas que trabaja durante los fines de semana o que env\u00eda correos electr\u00f3nicos a las 5.30 de la ma\u00f1ana y a las 9.30 de la noche, es hora de hablar con \u00e9l sobre la creaci\u00f3n de un mejor equilibrio entre la vida laboral y personal. Es hora de ver c\u00f3mo puedes apoyarles.  <\/p>\n\n<p class=\"wp-block-paragraph\">En resumen, necesitas preocuparte por tu gente. Apoyarles. Escucharlos. Responder cuando te planteen retos. Hazlo y fomentar\u00e1s una relaci\u00f3n basada en la confianza. Te corresponder\u00e1n con un aumento de la productividad y del esfuerzo discrecional.     <\/p>\n\n<p class=\"wp-block-paragraph\">Aqu\u00ed hemos vuelto sobre la importancia de un buen liderazgo. Consigues el seguimiento que merece tu estilo de liderazgo: no ocurre porque s\u00ed. Recuerda el punto anterior sobre Sandhurst: que los buenos l\u00edderes sirven a sus seguidores. Como l\u00edder, est\u00e1s ah\u00ed para proporcionar a tu gente todo lo que necesitan para hacer el trabajo por ti. Todo, desde el equipo y las herramientas hasta la motivaci\u00f3n y el prop\u00f3sito: una raz\u00f3n para levantarse de la cama por la ma\u00f1ana.    <\/p>\n\n<p class=\"wp-block-paragraph\">Si das a toda tu gente todo lo que necesita para ser brillante, conseguir\u00e1s un seguimiento eficaz. Sin esto, ning\u00fan l\u00edder puede tener \u00e9xito. Con \u00e9l, ning\u00fan l\u00edder puede fracasar.    <\/p>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">For more information about our Leadership Advisory Services, please contact <a href=\"mailto:t.mcewan@sheffieldhaworth.com\" target=\"_blank\" rel=\"noreferrer noopener\">Tim McEwan<\/a>.<\/h3>\n","protected":false},"excerpt":{"rendered":"<p>Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[430,392,363],"tags":[],"class_list":["post-25645","post","type-post","status-publish","format-standard","hentry","category-asesoria-de-liderazgo","category-liderazgo","category-perspectivas"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comprender el valor del seguimiento - Sheffield Haworth<\/title>\n<meta name=\"description\" content=\"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comprender el valor del seguimiento - Sheffield Haworth\" \/>\n<meta property=\"og:description\" content=\"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/\" \/>\n<meta property=\"og:site_name\" content=\"Sheffield Haworth\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-27T11:20:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T16:29:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/sh-default-social-card.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emberton92f71\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emberton92f71\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/\"},\"author\":{\"name\":\"emberton92f71\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\"},\"headline\":\"Comprender el valor del seguimiento\",\"datePublished\":\"2021-10-27T11:20:46+00:00\",\"dateModified\":\"2025-08-04T16:29:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/\"},\"wordCount\":1267,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\"},\"articleSection\":[\"Asesor\u00eda de Liderazgo\",\"Liderazgo\",\"Perspectivas\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/\",\"name\":\"Comprender el valor del seguimiento - Sheffield Haworth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#website\"},\"datePublished\":\"2021-10-27T11:20:46+00:00\",\"dateModified\":\"2025-08-04T16:29:29+00:00\",\"description\":\"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/comprender-el-valor-del-seguimiento\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/\",\"name\":\"Sheffield Haworth\",\"description\":\"Helping organisations and individuals to reach their potential\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#organization\",\"name\":\"Sheffield Haworth\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"width\":311,\"height\":151,\"caption\":\"Sheffield Haworth\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sheffield-haworth\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/es\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\",\"name\":\"emberton92f71\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"caption\":\"emberton92f71\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comprender el valor del seguimiento - Sheffield Haworth","description":"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/","og_locale":"es_ES","og_type":"article","og_title":"Comprender el valor del seguimiento - Sheffield Haworth","og_description":"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.","og_url":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/","og_site_name":"Sheffield Haworth","article_published_time":"2021-10-27T11:20:46+00:00","article_modified_time":"2025-08-04T16:29:29+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/sh-default-social-card.jpg","type":"image\/jpeg"}],"author":"emberton92f71","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emberton92f71","Est. reading time":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/#article","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/"},"author":{"name":"emberton92f71","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0"},"headline":"Comprender el valor del seguimiento","datePublished":"2021-10-27T11:20:46+00:00","dateModified":"2025-08-04T16:29:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/"},"wordCount":1267,"publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization"},"articleSection":["Asesor\u00eda de Liderazgo","Liderazgo","Perspectivas"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/","url":"https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/","name":"Comprender el valor del seguimiento - Sheffield Haworth","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#website"},"datePublished":"2021-10-27T11:20:46+00:00","dateModified":"2025-08-04T16:29:29+00:00","description":"Aunque todo el mundo parece querer ser un gran l\u00edder empresarial, es f\u00e1cil perder de vista por qu\u00e9 el seguimiento es igual de importante.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sheffieldhaworth.com\/es\/comprender-el-valor-del-seguimiento\/"]}]},{"@type":"WebSite","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#website","url":"https:\/\/www.sheffieldhaworth.com\/es\/","name":"Sheffield Haworth","description":"Helping organisations and individuals to reach their potential","publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sheffieldhaworth.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#organization","name":"Sheffield Haworth","url":"https:\/\/www.sheffieldhaworth.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","width":311,"height":151,"caption":"Sheffield Haworth"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/sheffield-haworth\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.sheffieldhaworth.com\/es\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0","name":"emberton92f71","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","caption":"emberton92f71"}}]}},"_links":{"self":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts\/25645","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/comments?post=25645"}],"version-history":[{"count":0,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/posts\/25645\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/media?parent=25645"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/categories?post=25645"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/es\/wp-json\/wp\/v2\/tags?post=25645"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}