{"id":20433,"date":"2023-10-23T10:59:39","date_gmt":"2023-10-23T09:59:39","guid":{"rendered":"https:\/\/www.sheffieldhaworth.com\/nicht-kategorisiert\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/"},"modified":"2025-04-25T19:36:44","modified_gmt":"2025-04-25T18:36:44","slug":"wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut","status":"publish","type":"post","link":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/","title":{"rendered":"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut"},"content":{"rendered":"\n<p>Die Forschung zeigt, dass neurodivergente Menschen erhebliche Schwierigkeiten haben, einen Arbeitsplatz zu finden und auch zu behalten. Untersuchungen von Unternehmen wie Deloitte zeigen jedoch, dass Teams mit neurodiversen Fachleuten in bestimmten Funktionen 30 % produktiver sein k\u00f6nnen als solche ohne sie. Dieser Mangel an Verst\u00e4ndnis f\u00fcr neurodiverse Menschen ist nicht nur unlogisch, sondern auch \u00e4u\u00dferst ungerecht. Dies gilt umso mehr, wenn wir bedenken, dass etwa einer von sieben Menschen neurodivergent ist.  <\/p>\n\n<p>Wir haben uns vor kurzem mit Vic Mazonas, dem Gesch\u00e4ftsf\u00fchrer von GAIN &#8211; der Gruppe f\u00fcr Autismus, Versicherung, Investment &amp; Neurodiversit\u00e4t &#8211; zusammengesetzt, um dar\u00fcber zu sprechen, wie er es als bekennender &#8222;sehr autistischer&#8220; Mensch geschafft hat, eine erfolgreiche Karriere zu machen. Welche Tipps haben sie zu bieten? Wie k\u00f6nnen Unternehmen mehr Verst\u00e4ndnis f\u00fcr die Bed\u00fcrfnisse von Neurodivergenten aufbringen und diese f\u00f6rdern? Und welche Schritte k\u00f6nnen neurodivergente Menschen selbst am Arbeitsplatz unternehmen, um ihre Erfolgschancen zu verbessern?   <\/p>\n\n<p><strong>F: Wie waren Ihre Erfahrungen in der Schule?<\/strong><\/p>\n\n<p><strong>A:<\/strong> Meine Schulzeit war eine gemischte Sache. Ich wurde aufgrund meiner akademischen F\u00e4higkeiten als hochbegabt eingestuft, aber bei mir klaffte eine gro\u00dfe L\u00fccke zwischen akademischer Intelligenz und emotionaler Intelligenz und sozialen F\u00e4higkeiten. <\/p>\n\n<p>Ich war zwar gut in der Schule, aber ich langweilte mich oft im Unterricht. Au\u00dferhalb des Unterrichts gab es viel soziale Ausgrenzung und Mobbing. Meine Mitsch\u00fcler wussten, dass ich anders war als sie, auch wenn wir damals noch keine Bezeichnung daf\u00fcr hatten.  <\/p>\n\n<p>Es hilft, dass ich das Lernen schon immer geliebt habe. Auch wenn ich in der Schule mit den Aufgaben, die mir gestellt wurden, unterfordert war, habe ich jede Gelegenheit genutzt, um etwas Neues zu lernen. Ich nahm an so vielen Clubs nach der Schule und in der Mittagspause teil, wie ich konnte. Au\u00dferhalb der Schule verfolgte ich viele meiner eigenen Interessen wie Schreiben, Kunst, Lesen \u00fcber Arch\u00e4ologie und Wissenschaft. Au\u00dferdem hatte ich eine liebevolle Familie, was mir sehr geholfen hat.    <\/p>\n\n<p><strong>F: Vor welchen Herausforderungen standen Sie aufgrund Ihrer Neurodivergenz bei Ihren Aufgaben nach der Universit\u00e4t und wie sind Sie damit umgegangen?<\/strong><\/p>\n\n<p><strong>A:<\/strong> Umgebungsger\u00e4usche k\u00f6nnen \u00fcberw\u00e4ltigend sein. Wenn mehrere Personen gleichzeitig sprechen, selbst wenn sie alle leise sprechen, finde ich es schwierig, die Stimme herauszuh\u00f6ren, auf die ich mich konzentrieren soll. <\/p>\n\n<p>Wenn es sich um ein Gro\u00dfraumb\u00fcro handelt, werden Ger\u00e4usche widerhallen und mich ablenken. Helles Licht kann eine Herausforderung sein. Auch k\u00f6rperliche Empfindungen, z. B. wenn der B\u00fcrostuhl eine raue Struktur auf der Sitzfl\u00e4che hat, kann ich dies durch meine Kleidung hindurch sp\u00fcren und bin dann frustriert.  <\/p>\n\n<p><strong><em>&#8222;Es geht nicht nur darum, zu lernen, den versteckten Subtext in der Kommunikation anderer Menschen zu verstehen, sondern auch darum, den zuf\u00e4lligen Subtext zu erkennen, von dem ich nicht wei\u00df, dass ich ihn kommuniziere.&#8220;<\/em><\/strong><\/p>\n\n<p>Ich kann sehr direkt und unverbl\u00fcmt sein, und es hat lange gedauert, bis ich gelernt habe, so zu sein, ohne dabei stumpf oder unh\u00f6flich zu wirken oder so, als ob ich kein Interesse an der anderen Person h\u00e4tte. Manchmal dachte ich, dass ich bei meinen Entscheidungen \u00fcberlegt und vorsichtig vorgehen w\u00fcrde. Und mir war nicht klar, dass die Wahrnehmung der anderen eigentlich das Gegenteil war.  <\/p>\n\n<p>Ich habe festgestellt, dass f\u00fcr neurotypische Menschen &#8211; Menschen, die nicht neurodivers sind &#8211; die w\u00f6rtlichen Worte, die in einem Gespr\u00e4ch gesagt werden, viel weniger wichtig sind als der Kontext, in dem sie stehen. Wenn ich hingegen etwas sage, meine ich genau die Worte, die aus meinem Mund kommen. Und es geht nicht nur darum zu lernen, den versteckten Subtext in der Kommunikation anderer Menschen zu verstehen, sondern auch darum, den zuf\u00e4lligen Subtext zu erkennen, von dem ich nicht wei\u00df, dass ich ihn kommuniziere.  <\/p>\n\n<p><strong>F: Wie machen Sie das? Welche Strategien haben Ihnen geholfen, damit umzugehen? <\/strong><\/p>\n\n<p><strong>A:<\/strong> Sehr lange Zeit war ich einfach sehr schlecht. Es ging darum, jemanden aus Versehen zu verletzen oder zu ver\u00e4rgern, herauszufinden, warum das passiert war, mich zu entschuldigen, meine Absicht zu erkl\u00e4ren und dann vorw\u00e4rts zu gehen und zu versuchen, die Muster zu finden, nach denen diese Situationen auftraten. <\/p>\n\n<p>Ich bin nicht gut im Umgang mit Menschen, aber ich bin gut in der Mustererkennung und der Analyse von Daten. Ich begann, diese F\u00e4higkeit zu nutzen, um die Situationen, in denen ich Schwierigkeiten hatte, zu analysieren und ihnen einen Sinn zu geben. Das war alles, bevor ich wusste, dass ich autistisch bin.  <\/p>\n\n<p>Ich war Mitte bis Ende 20, als ich begann zu begreifen, dass andere Menschen nicht damit zurechtkommen. Ich n\u00e4herte mich dem Alter von 30 Jahren, als ein Freund von mir auf ADHS und Autismus untersucht wurde, und mir wurde klar, dass viele der Dinge in den diagnostischen Tests sehr danach klangen, was ich mir unter einem normalen Leben vorstellte. <\/p>\n\n<p>Danach habe ich festgestellt, dass es sehr hilft, offen zu sein. Wenn ich in ein neues Team komme, sage ich den Leuten, dass ich sehr autistisch bin und bitte sie, mir zu sagen, wenn ich etwas Falsches sage. <\/p>\n\n<p><strong>F: Wenn man bedenkt, dass Sie jetzt eine sehr interessante Rolle bei der Unterst\u00fctzung der neurodiversen Gemeinschaft innehaben, was sind Ihrer Meinung nach die wichtigsten Faktoren, die zum Erfolg am Arbeitsplatz beitragen?<\/strong><\/p>\n\n<p><strong>A:<\/strong> Ein Teil meines Erfolges besteht darin, dass ich ein Sturkopf bin und nicht gerne h\u00f6re, dass mir jemand etwas nicht zutraut. Wenn ich vor eine Herausforderung gestellt werde, st\u00fcrze ich mich kopf\u00fcber darauf. <\/p>\n\n<p>Ein weiterer Faktor, der zu meinem Erfolg beigetragen hat, ist meine direkte Art. Es f\u00e4llt mir wirklich schwer, nicht offen \u00fcber mich zu sprechen. Ich bin LGBTQ und habe mich einmal aus Versehen einem Freund gegen\u00fcber geoutet, als dieser etwas Wohlmeinendes, aber Ignorantes \u00fcber eine Gruppe von Menschen sagte. Ich sagte: &#8222;Nun, ich geh\u00f6re dazu.&#8220; Erst danach wurde mir klar, dass ich mich geoutet hatte.    <\/p>\n\n<p><strong><em>&#8222;Ich habe Gl\u00fcck, dass ich in einer sehr akzeptierenden Gegend aufgewachsen bin, denn ich h\u00e4tte es nicht geschafft, im Schrank zu bleiben, wenn ich es h\u00e4tte tun m\u00fcssen!&#8220;<\/em><\/strong><\/p>\n\n<p>Ich habe Gl\u00fcck, dass ich in einer sehr akzeptierenden Gegend aufgewachsen bin, denn es w\u00e4re mir nicht leicht gefallen, mich zu verstecken, wenn ich es h\u00e4tte tun m\u00fcssen! Aber ich bin so gut wie unf\u00e4hig zu l\u00fcgen. <\/p>\n\n<p>Wenn ich versuche, einen netteren Weg zu finden, etwas zu sagen, gehe ich manchmal sogar so weit zu sagen, dass ich bef\u00fcrchte, stumpf zu werden. Ich bin nicht gut im ersten Eindruck, aber mir liegen andere Menschen sehr am Herzen und es ist mir wichtig, dass ich f\u00fcr andere hilfreich bin. Auch wenn ich manchmal aufgrund meiner sozialen Inkompetenz einen schlechten ersten Eindruck hinterlasse, merken die Leute, wenn sie mich kennen und mit mir arbeiten, dass ich mich um sie k\u00fcmmere.  <\/p>\n\n<p>Wenn ich meine unverbl\u00fcmte Ehrlichkeit nutze, um freundlich zu sein und nicht als Ausrede, um gemein zu sein, hat das bis zu einem gewissen Grad dazu beigetragen, dass die Menschen meine guten Absichten erkennen.<\/p>\n\n<p><strong>F: Was Sie gesagt haben, zeigt, wie wichtig es ist, der neurodiversen Bev\u00f6lkerung eine Chance zu geben, zu zeigen, was sie kann. Was glauben Sie, bringen Sie sonst noch in eine Organisation ein? <\/strong><\/p>\n\n<p><strong>A:<\/strong> Einige der Dinge, die ich mitbringe, sind solche, auf die ich pers\u00f6nlich sehr stolz bin und die mit meinem Autismus zu tun haben. Ich liebe es zu lernen und bin immer bestrebt, mir neue Informationen selbst\u00e4ndig anzueignen. <\/p>\n\n<p>Ein Teil des Stereotyps von Autisten ist ein Mangel an Empathie. Dieses Klischee ist nicht nur v\u00f6llig falsch, sondern ich denke oft, dass wir das Gegenteil davon haben. Die meisten Autisten, die ich kenne &#8211; mich eingeschlossen &#8211; haben etwas, das man Hyperempathie nennt. Oder zumindest ein \u00dcberma\u00df an Empathie, bei dem wir uns so sehr um andere k\u00fcmmern.   <\/p>\n\n<p>Wenn ich in die Arbeit, die ich tue, und in das Team, dem ich angeh\u00f6re, investiert bin, liegt mir viel daran, dass das Team funktioniert. Der Erfolg des Teams liegt mir mehr am Herzen als mein eigener Erfolg. <\/p>\n\n<p>Ich bin ein nat\u00fcrlicher Probleml\u00f6ser. Aufgrund meiner F\u00e4higkeit, Muster zu erkennen, finde ich potenzielle Probleme, bevor sie zu Problemen werden, und entwickle Strategien, um sie zu l\u00f6sen. Und es macht mir Spa\u00df, die vage Idee einer anderen Person aufzugreifen und die praktischen Schritte zu entwerfen, um sie in die Tat umzusetzen und dann zu verwirklichen.  <\/p>\n\n<p><strong>F: Erfolg h\u00e4ngt oft von der Hilfe ab, die wir von anderen erhalten, aber auch von unseren eigenen Bem\u00fchungen. Welche Art von Unterst\u00fctzung haben Sie in Ihrer Karriere erhalten? <\/strong><\/p>\n\n<p><strong>A:<\/strong> Da ich in meiner derzeitigen Rolle haupts\u00e4chlich von zu Hause aus arbeite, gibt es weniger Unterst\u00fctzung in Bezug auf die Umgebung. Aber normalerweise nimmt mein Team unsere Besprechungen auf und transkribiert sie, so dass ich nicht zwischen Notizen und Zuh\u00f6ren und aktiver Teilnahme an der Konversation w\u00e4hlen muss. Ich kann aktiv an dem Gespr\u00e4ch teilnehmen, w\u00e4hrend es stattfindet.  <\/p>\n\n<p>In meiner vorherigen Rolle hatte ich viel Hilfe in Bezug auf die sensorische Umgebung. Ich durfte den ganzen Tag im B\u00fcro Kopfh\u00f6rer tragen, um die Umgebungsger\u00e4usche auszublenden. Wenn der Raum zu hell oder zu voll war, konnte ich f\u00fcr den Nachmittag einen kleinen ruhigen Besprechungsraum buchen.  <\/p>\n\n<p><strong><em>&#8222;Man kann gar nicht genug betonen, wie wichtig der richtige Manager sein kann, besonders f\u00fcr neurodiverse Menschen.<\/em><\/strong><\/p>\n\n<p>Mein damaliger Manager war sehr gut darin, den Subtext zu erkl\u00e4ren. Nach einem Meeting oder einer E-Mail, deren Ergebnis nicht das war, was ich erwartet hatte, ging ich mit ihm zur Seite und fragte ihn, was passiert war. Er war gut darin, mir den unsichtbaren Kontext und Dinge zu erkl\u00e4ren, die andere vielleicht nicht laut aussprechen wollten, ohne die ich aber nicht die richtigen n\u00e4chsten Schritte herausfinden konnte.  <\/p>\n\n<p>Man kann gar nicht hoch genug einsch\u00e4tzen, welchen Einfluss die richtige F\u00fchrungskraft haben kann, insbesondere f\u00fcr neurodiverse Menschen. Wenn ich auf die Stellen zur\u00fcckblicke, in denen meine Karriere nicht so gut verlief, und sie mit den Stellen vergleiche, in denen ich Erfolg hatte, dann lag es in jedem einzelnen Fall an der Herangehensweise des Managers, daran, wie er sein Team f\u00fchrte, wie er die Bed\u00fcrfnisse und W\u00fcnsche der Teammitglieder interpretierte und was er als seine Rolle in der Abteilung ansah. Die Manager, die sich um ihr Team k\u00fcmmerten, waren immer gro\u00dfartig.  <\/p>\n\n<p><strong>F: Was sollten Unternehmen tun, um die Neurodiversit\u00e4t wirklich zu f\u00f6rdern und ihre Mitarbeiter zu ermutigen, ihre Bed\u00fcrfnisse zu \u00e4u\u00dfern?<\/strong><\/p>\n\n<p><strong>A:<\/strong> Wenn das Team und der Manager gut sind, werden die Mitarbeiter loyal sein, egal was passiert. Die psychologische Sicherheit am Arbeitsplatz ist ein wichtiger Bestandteil der Ma\u00dfnahmen. Wenn Sie neurodivergente Menschen besch\u00e4ftigen, wissen Sie meist nicht, dass Sie sie besch\u00e4ftigen.  <\/p>\n\n<p>Aber ich garantiere Ihnen, dass die meisten neurodivergenten Menschen mindestens eine, wenn nicht sogar mehrere schlechte Erfahrungen an einem fr\u00fcheren Arbeitsplatz gemacht haben, an dem sie gemobbt oder als inkompetent behandelt wurden. Wo sie bei Bef\u00f6rderungen \u00fcbergangen wurden, weil sie nicht laut genug mit ihren eigenen Leistungen im Vergleich zu anderen geprahlt haben. Die Offenlegung von besonderen Bed\u00fcrfnissen kann also oft sehr be\u00e4ngstigend sein.  <\/p>\n\n<p>Das Beste, was Sie daher tun k\u00f6nnen, ist, auf Diagnosen und Arztbriefe als Beweis f\u00fcr den Bedarf zu verzichten. Behandeln Sie stattdessen alle Ihre Mitarbeiter so, als w\u00e4ren sie Menschen, deren einzigartige Bed\u00fcrfnisse und Herausforderungen g\u00fcltig und wichtig sind. <\/p>\n\n<p><strong><em>&#8222;Wenn Sie von der Perspektive ausgehen, wie Sie die bestm\u00f6gliche Person aus den Menschen, mit denen Sie arbeiten, herausholen k\u00f6nnen&#8230; werden sich die Menschen Ihnen gegen\u00fcber \u00f6ffnen.&#8220;<\/em><\/strong><\/p>\n\n<p>Ich sagte bereits, dass ich in einer offenen Umgebung gerne Kopfh\u00f6rer aufsetze, weil sie die Umgebungsger\u00e4usche, die mich ablenken, \u00fcbert\u00f6nen. Wenn ich das nun brauche, um mich besser konzentrieren zu k\u00f6nnen, und mein Kollege, der neben mir sitzt und nicht autistisch ist, einfach gl\u00fccklicher und produktiver ist, wenn er Musik h\u00f6rt, spielt es dann eine Rolle, dass wir aus unterschiedlichen Gr\u00fcnden das Gleiche brauchen? Welchen Sinn h\u00e4tte es, bei mir ja und bei ihm nein zu sagen?  <\/p>\n\n<p>Wenn Sie von der Perspektive ausgehen, wie Sie die bestm\u00f6gliche Person aus Ihren Mitarbeitern herausholen k\u00f6nnen, was sie am gl\u00fccklichsten und motiviertesten macht, was sie inspiriert oder begeistert, werden sich die Mitarbeiter Ihnen gegen\u00fcber \u00f6ffnen, wenn sie sich sicher f\u00fchlen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN<\/p>\n","protected":false},"author":12,"featured_media":20437,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[309,310],"tags":[],"class_list":["post-20433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einblicke","category-vielfalt-gleichberechtigung-inklusion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth<\/title>\n<meta name=\"description\" content=\"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth\" \/>\n<meta property=\"og:description\" content=\"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/\" \/>\n<meta property=\"og:site_name\" content=\"Sheffield Haworth\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T09:59:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-25T18:36:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"emberton92f71\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"emberton92f71\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/\"},\"author\":{\"name\":\"emberton92f71\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\"},\"headline\":\"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut\",\"datePublished\":\"2023-10-23T09:59:39+00:00\",\"dateModified\":\"2025-04-25T18:36:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/\"},\"wordCount\":2096,\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/photo-1711861982569-565113102217-scaled.jpg\",\"articleSection\":[\"Einblicke\",\"Vielfalt, Gleichberechtigung &amp; Inklusion\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/\",\"name\":\"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/photo-1711861982569-565113102217-scaled.jpg\",\"datePublished\":\"2023-10-23T09:59:39+00:00\",\"dateModified\":\"2025-04-25T18:36:44+00:00\",\"description\":\"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/photo-1711861982569-565113102217-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/photo-1711861982569-565113102217-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/\",\"name\":\"Sheffield Haworth\",\"description\":\"Organisationen und Einzelpersonen dabei helfen, ihr Potenzial auszusch\u00f6pfen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#organization\",\"name\":\"Sheffield Haworth\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"width\":311,\"height\":151,\"caption\":\"Sheffield Haworth\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sheffield-haworth\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/person\\\/6a8fdcb00da3afdbff4cb63efc8be2f0\",\"name\":\"emberton92f71\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g\",\"caption\":\"emberton92f71\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth","description":"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/","og_locale":"de_DE","og_type":"article","og_title":"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth","og_description":"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN","og_url":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/","og_site_name":"Sheffield Haworth","article_published_time":"2023-10-23T09:59:39+00:00","article_modified_time":"2025-04-25T18:36:44+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg","type":"image\/jpeg"}],"author":"emberton92f71","twitter_card":"summary_large_image","twitter_misc":{"Written by":"emberton92f71","Est. reading time":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/#article","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/"},"author":{"name":"emberton92f71","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0"},"headline":"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut","datePublished":"2023-10-23T09:59:39+00:00","dateModified":"2025-04-25T18:36:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/"},"wordCount":2096,"publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#organization"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg","articleSection":["Einblicke","Vielfalt, Gleichberechtigung &amp; Inklusion"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/","url":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/","name":"Wie man eine erfolgreiche Karriere als neurodiverse Person aufbaut - Sheffield Haworth","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/#primaryimage"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg","datePublished":"2023-10-23T09:59:39+00:00","dateModified":"2025-04-25T18:36:44+00:00","description":"Eine Frage und Antwort mit Vic Mazonas, General Manager von GAIN","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sheffieldhaworth.com\/de\/wie-man-eine-erfolgreiche-karriere-als-neurodiverse-person-aufbaut\/#primaryimage","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/01\/photo-1711861982569-565113102217-scaled.jpg","width":2560,"height":1440},{"@type":"WebSite","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#website","url":"https:\/\/www.sheffieldhaworth.com\/de\/","name":"Sheffield Haworth","description":"Organisationen und Einzelpersonen dabei helfen, ihr Potenzial auszusch\u00f6pfen","publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sheffieldhaworth.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#organization","name":"Sheffield Haworth","url":"https:\/\/www.sheffieldhaworth.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","width":311,"height":151,"caption":"Sheffield Haworth"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/sheffield-haworth\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/person\/6a8fdcb00da3afdbff4cb63efc8be2f0","name":"emberton92f71","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/140c25bac9eb57d35054fa81f24703d0c8a5e3c0855dfff4cdaaee04536366bc?s=96&d=mm&r=g","caption":"emberton92f71"}}]}},"_links":{"self":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/posts\/20433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/comments?post=20433"}],"version-history":[{"count":0,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/posts\/20433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/media\/20437"}],"wp:attachment":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/media?parent=20433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/categories?post=20433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/tags?post=20433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}