{"id":21446,"date":"2024-09-04T21:53:38","date_gmt":"2024-09-04T20:53:38","guid":{"rendered":"https:\/\/www.sheffieldhaworth.com\/karriere\/"},"modified":"2025-08-26T17:12:13","modified_gmt":"2025-08-26T16:12:13","slug":"karriere","status":"publish","type":"page","link":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/","title":{"rendered":"Karriere"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"21446\" class=\"elementor elementor-21446 elementor-12222\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-336488f page-title e-flex e-con-boxed e-con e-parent\" data-id=\"336488f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-851f531 e-con-full e-flex e-con e-child\" data-id=\"851f531\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67086b0 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"67086b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"22\" viewBox=\"0 0 24 22\" fill=\"none\"><mask id=\"mask0_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"22\"><path d=\"M24 0H0V21.6H24V0Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask0_42_10913)\"><mask id=\"mask1_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"24\" height=\"22\"><path d=\"M24 0H0V21.6H24V0Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask1_42_10913)\"><mask id=\"mask2_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"1\" y=\"1\" width=\"23\" height=\"20\"><path d=\"M23.0474 1.5H1.52344V20.544H23.0474V1.5Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask2_42_10913)\"><path d=\"M22.7353 18.1879C22.7353 19.4879 21.6633 20.5399 20.3433 20.5399C19.0193 20.5399 17.9473 19.4879 17.9473 18.1879C17.9473 16.8879 19.0193 15.8359 20.3433 15.8359C21.6673 15.8359 22.7353 16.8879 22.7353 18.1879Z\" fill=\"white\"><\/path><\/g><mask id=\"mask3_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"1\" y=\"1\" width=\"23\" height=\"20\"><path d=\"M23.0474 1.5H1.52344V20.544H23.0474V1.5Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask3_42_10913)\"><path d=\"M17.292 18.1879C17.292 19.4879 16.22 20.5399 14.896 20.5399C13.572 20.5399 12.5 19.4879 12.5 18.1879C12.5 16.8879 13.572 15.8359 14.896 15.8359C16.22 15.8359 17.292 16.8879 17.292 18.1879Z\" fill=\"white\"><\/path><\/g><path d=\"M14.8987 14.7678C16.1004 14.7678 17.0747 13.8097 17.0747 12.6278C17.0747 11.4459 16.1004 10.4878 14.8987 10.4878C13.6969 10.4878 12.7227 11.4459 12.7227 12.6278C12.7227 13.8097 13.6969 14.7678 14.8987 14.7678Z\" fill=\"white\"><\/path><path d=\"M22.5161 12.6278C22.5161 13.8078 21.5401 14.7678 20.3401 14.7678C19.1401 14.7678 18.1641 13.8078 18.1641 12.6278C18.1641 11.4478 19.1361 10.4878 20.3401 10.4878C21.5441 10.4878 22.5161 11.4478 22.5161 12.6278Z\" fill=\"white\"><\/path><path d=\"M14.9002 9.20378C15.8611 9.20378 16.6402 8.4373 16.6402 7.49178C16.6402 6.54627 15.8611 5.77979 14.9002 5.77979C13.9392 5.77979 13.1602 6.54627 13.1602 7.49178C13.1602 8.4373 13.9392 9.20378 14.9002 9.20378Z\" fill=\"white\"><\/path><path d=\"M22.0796 7.49178C22.0796 8.43578 21.2996 9.20378 20.3396 9.20378C19.3796 9.20378 18.5996 8.43578 18.5996 7.49178C18.5996 6.54778 19.3796 5.77979 20.3396 5.77979C21.2996 5.77979 22.0796 6.54778 22.0796 7.49178Z\" fill=\"white\"><\/path><mask id=\"mask4_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"1\" y=\"1\" width=\"23\" height=\"20\"><path d=\"M23.0474 1.5H1.52344V20.544H23.0474V1.5Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask4_42_10913)\"><path d=\"M12.0674 18.1879C12.0674 19.4879 10.9954 20.5399 9.67139 20.5399C8.34739 20.5399 7.27539 19.4879 7.27539 18.1879C7.27539 16.8879 8.34739 15.8359 9.67139 15.8359C10.9954 15.8359 12.0674 16.8879 12.0674 18.1879Z\" fill=\"white\"><\/path><\/g><path d=\"M11.852 12.6278C11.852 13.8078 10.876 14.7678 9.676 14.7678C8.476 14.7678 7.5 13.8078 7.5 12.6278C7.5 11.4478 8.476 10.4878 9.676 10.4878C10.876 10.4878 11.852 11.4478 11.852 12.6278Z\" fill=\"white\"><\/path><mask id=\"mask5_42_10913\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"1\" y=\"1\" width=\"23\" height=\"20\"><path d=\"M23.0474 1.5H1.52344V20.544H23.0474V1.5Z\" fill=\"white\"><\/path><\/mask><g mask=\"url(#mask5_42_10913)\"><path d=\"M6.62795 18.1879C6.62795 19.4879 5.55593 20.5399 4.23193 20.5399C2.90793 20.5399 1.83594 19.4879 1.83594 18.1879C1.83594 16.8879 2.90793 15.8359 4.23193 15.8359C5.55593 15.8359 6.62795 16.8879 6.62795 18.1879Z\" fill=\"white\"><\/path><\/g><path d=\"M21.8625 2.996C21.8625 3.824 21.1825 4.496 20.3385 4.496C19.4945 4.496 18.8145 3.824 18.8145 2.996C18.8145 2.168 19.4945 1.5 20.3385 1.5C21.1825 1.5 21.8625 2.172 21.8625 2.996Z\" fill=\"white\"><\/path><\/g><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-479af94 elementor-widget elementor-widget-heading\" data-id=\"479af94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><span style=\"font-size: 16px;text-align: center;text-transform: uppercase\">Karriere<\/span><span style=\"font-size: 16px;text-align: center;text-transform: uppercase\"><\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf89adf e-con-full e-flex e-con e-child\" data-id=\"cf89adf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-441ce80 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"441ce80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Karriere bei Sheffield Haworth<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efb6f24 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"efb6f24\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6ea91ca e-flex e-con-boxed e-con e-parent\" data-id=\"6ea91ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0970206 e-con-full e-flex e-con e-child\" data-id=\"0970206\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44e0dc4 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"44e0dc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Um unseren Kunden die besten L\u00f6sungen anbieten zu k\u00f6nnen, m\u00fcssen wir die besten Talente einstellen.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe236f6 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fe236f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die sich schnell entwickelnde Wirtschaft von heute ist auf Talente angewiesen. Die richtigen F\u00e4higkeiten und die richtigen Mitarbeiter sind der Motor f\u00fcr die erfolgreichen Unternehmen, Scale-ups und Organisationen der Zukunft. <\/p><p>Hier kommen Sie ins Spiel.<\/p><p>Eine gro\u00dfe Talentberatung braucht gro\u00dfe Talente. Ob Sie nun ein hervorragender Hochschulabsolvent sind, der in dieser dynamischen und aufregenden Branche Fu\u00df fassen m\u00f6chte, oder ob Sie ein erfahrener Veteran mit einem umfangreichen Netzwerk sind, der sein Fachgebiet weiterentwickeln und ausbauen m\u00f6chte, dann k\u00f6nnte eine Karriere bei Sheffield Haworth genau das Richtige f\u00fcr Sie sein. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a0f6f3b e-con-full e-flex e-con e-child\" data-id=\"a0f6f3b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19776e7 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"19776e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Kommen Sie zu Sheffield Haworth und arbeiten Sie mit einigen der gr\u00f6\u00dften und interessantesten Unternehmen der Welt zusammen, um deren Talentprobleme zu l\u00f6sen. Wir k\u00f6nnen auf eine 30-j\u00e4hrige Erfolgsgeschichte in vielen Branchen zur\u00fcckblicken und verf\u00fcgen \u00fcber ein globales Team, das in 12 Niederlassungen weltweit t\u00e4tig ist. Bei Sheffield Haworth erhalten Sie die Agilit\u00e4t eines schnell wachsenden Herausforderers mit den Vorteilen der Arbeit in einem etablierten Unternehmen mit engen Kundenbeziehungen und der M\u00f6glichkeit, wirklich etwas zu bewirken.  <\/p><p><br>Sie werden starke Beziehungen zu anderen Mitarbeitern auf der ganzen Welt kn\u00fcpfen, kollaborativ arbeiten und dabei unterst\u00fctzt werden, Ihr Potenzial auszusch\u00f6pfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-30094b9 e-flex e-con-boxed e-con e-parent\" data-id=\"30094b9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1a579da e-con-full e-flex e-con e-child\" data-id=\"1a579da\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55edde4 elementor-widget elementor-widget-heading\" data-id=\"55edde4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wie wir unsere Mitarbeiter unterst\u00fctzen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c15c5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"44c15c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir unterst\u00fctzen und f\u00f6rdern unsere Mitarbeiter, damit sie brillante Dinge tun k\u00f6nnen:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-103a01e e-con-full e-flex e-con e-child\" data-id=\"103a01e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-f3f9d35 e-con-full e-flex e-con e-child\" data-id=\"f3f9d35\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b9d519 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2b9d519\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjEyMTIsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"14\" viewBox=\"0 0 48 14\" fill=\"none\"><path d=\"M46.7767 7.69254L41.1517 13.3175C41.0345 13.4348 40.8754 13.5007 40.7095 13.5007C40.5437 13.5007 40.3846 13.4348 40.2673 13.3175C40.1501 13.2003 40.0842 13.0412 40.0842 12.8753C40.0842 12.7095 40.1501 12.5504 40.2673 12.4332L44.8259 7.87535H1.625C1.45924 7.87535 1.30027 7.8095 1.18306 7.69229C1.06585 7.57508 1 7.41611 1 7.25035C1 7.08459 1.06585 6.92562 1.18306 6.80841C1.30027 6.6912 1.45924 6.62535 1.625 6.62535H44.8259L40.2673 2.06753C40.1501 1.95026 40.0842 1.7912 40.0842 1.62535C40.0842 1.4595 40.1501 1.30044 40.2673 1.18316C40.3846 1.06588 40.5437 1 40.7095 1C40.8754 1 41.0345 1.06588 41.1517 1.18316L46.7767 6.80816C46.8348 6.86621 46.8809 6.93514 46.9124 7.01101C46.9438 7.08688 46.96 7.16821 46.96 7.25035C46.96 7.33248 46.9438 7.41381 46.9124 7.48969C46.8809 7.56556 46.8348 7.63449 46.7767 7.69254Z\" fill=\"#2C2D82\" stroke=\"#2C2D82\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Belohnung und Anerkennung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5ea6ed e-con-full e-flex e-con e-child\" data-id=\"b5ea6ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-995a980 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"995a980\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjE0ODUsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"14\" viewBox=\"0 0 48 14\" fill=\"none\"><path d=\"M46.7767 7.69254L41.1517 13.3175C41.0345 13.4348 40.8754 13.5007 40.7095 13.5007C40.5437 13.5007 40.3846 13.4348 40.2673 13.3175C40.1501 13.2003 40.0842 13.0412 40.0842 12.8753C40.0842 12.7095 40.1501 12.5504 40.2673 12.4332L44.8259 7.87535H1.625C1.45924 7.87535 1.30027 7.8095 1.18306 7.69229C1.06585 7.57508 1 7.41611 1 7.25035C1 7.08459 1.06585 6.92562 1.18306 6.80841C1.30027 6.6912 1.45924 6.62535 1.625 6.62535H44.8259L40.2673 2.06753C40.1501 1.95026 40.0842 1.7912 40.0842 1.62535C40.0842 1.4595 40.1501 1.30044 40.2673 1.18316C40.3846 1.06588 40.5437 1 40.7095 1C40.8754 1 41.0345 1.06588 41.1517 1.18316L46.7767 6.80816C46.8348 6.86621 46.8809 6.93514 46.9124 7.01101C46.9438 7.08688 46.96 7.16821 46.96 7.25035C46.96 7.33248 46.9438 7.41381 46.9124 7.48969C46.8809 7.56556 46.8348 7.63449 46.7767 7.69254Z\" fill=\"#2C2D82\" stroke=\"#2C2D82\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kultur und Erfahrung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a3b55c e-con-full e-flex e-con e-child\" data-id=\"1a3b55c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bc595b6 e-con-full e-flex e-con e-child\" data-id=\"bc595b6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-029c9d4 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"029c9d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjEyMzMsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"14\" viewBox=\"0 0 48 14\" fill=\"none\"><path d=\"M46.7767 7.69254L41.1517 13.3175C41.0345 13.4348 40.8754 13.5007 40.7095 13.5007C40.5437 13.5007 40.3846 13.4348 40.2673 13.3175C40.1501 13.2003 40.0842 13.0412 40.0842 12.8753C40.0842 12.7095 40.1501 12.5504 40.2673 12.4332L44.8259 7.87535H1.625C1.45924 7.87535 1.30027 7.8095 1.18306 7.69229C1.06585 7.57508 1 7.41611 1 7.25035C1 7.08459 1.06585 6.92562 1.18306 6.80841C1.30027 6.6912 1.45924 6.62535 1.625 6.62535H44.8259L40.2673 2.06753C40.1501 1.95026 40.0842 1.7912 40.0842 1.62535C40.0842 1.4595 40.1501 1.30044 40.2673 1.18316C40.3846 1.06588 40.5437 1 40.7095 1C40.8754 1 41.0345 1.06588 41.1517 1.18316L46.7767 6.80816C46.8348 6.86621 46.8809 6.93514 46.9124 7.01101C46.9438 7.08688 46.96 7.16821 46.96 7.25035C46.96 7.33248 46.9438 7.41381 46.9124 7.48969C46.8809 7.56556 46.8348 7.63449 46.7767 7.69254Z\" fill=\"#2C2D82\" stroke=\"#2C2D82\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Entwicklung von Menschen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3e13ed e-con-full e-flex e-con e-child\" data-id=\"d3e13ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-356a0dc elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"356a0dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjEyMTksInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"14\" viewBox=\"0 0 48 14\" fill=\"none\"><path d=\"M46.7767 7.69254L41.1517 13.3175C41.0345 13.4348 40.8754 13.5007 40.7095 13.5007C40.5437 13.5007 40.3846 13.4348 40.2673 13.3175C40.1501 13.2003 40.0842 13.0412 40.0842 12.8753C40.0842 12.7095 40.1501 12.5504 40.2673 12.4332L44.8259 7.87535H1.625C1.45924 7.87535 1.30027 7.8095 1.18306 7.69229C1.06585 7.57508 1 7.41611 1 7.25035C1 7.08459 1.06585 6.92562 1.18306 6.80841C1.30027 6.6912 1.45924 6.62535 1.625 6.62535H44.8259L40.2673 2.06753C40.1501 1.95026 40.0842 1.7912 40.0842 1.62535C40.0842 1.4595 40.1501 1.30044 40.2673 1.18316C40.3846 1.06588 40.5437 1 40.7095 1C40.8754 1 41.0345 1.06588 41.1517 1.18316L46.7767 6.80816C46.8348 6.86621 46.8809 6.93514 46.9124 7.01101C46.9438 7.08688 46.96 7.16821 46.96 7.25035C46.96 7.33248 46.9438 7.41381 46.9124 7.48969C46.8809 7.56556 46.8348 7.63449 46.7767 7.69254Z\" fill=\"#2C2D82\" stroke=\"#2C2D82\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Gesundheit und Wohlbefinden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-10c7d6c e-con-full e-flex e-con e-child\" data-id=\"10c7d6c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8564850 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"8564850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6MjEyMTYsInRvZ2dsZSI6ZmFsc2V9\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"48\" height=\"14\" viewBox=\"0 0 48 14\" fill=\"none\"><path d=\"M46.7767 7.69254L41.1517 13.3175C41.0345 13.4348 40.8754 13.5007 40.7095 13.5007C40.5437 13.5007 40.3846 13.4348 40.2673 13.3175C40.1501 13.2003 40.0842 13.0412 40.0842 12.8753C40.0842 12.7095 40.1501 12.5504 40.2673 12.4332L44.8259 7.87535H1.625C1.45924 7.87535 1.30027 7.8095 1.18306 7.69229C1.06585 7.57508 1 7.41611 1 7.25035C1 7.08459 1.06585 6.92562 1.18306 6.80841C1.30027 6.6912 1.45924 6.62535 1.625 6.62535H44.8259L40.2673 2.06753C40.1501 1.95026 40.0842 1.7912 40.0842 1.62535C40.0842 1.4595 40.1501 1.30044 40.2673 1.18316C40.3846 1.06588 40.5437 1 40.7095 1C40.8754 1 41.0345 1.06588 41.1517 1.18316L46.7767 6.80816C46.8348 6.86621 46.8809 6.93514 46.9124 7.01101C46.9438 7.08688 46.96 7.16821 46.96 7.25035C46.96 7.33248 46.9438 7.41381 46.9124 7.48969C46.8809 7.56556 46.8348 7.63449 46.7767 7.69254Z\" fill=\"#2C2D82\" stroke=\"#2C2D82\" stroke-width=\"0.5\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Agiles Arbeiten<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0c80f78 e-con-full e-flex e-con e-child\" data-id=\"0c80f78\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b25d87d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b25d87d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie mehr dar\u00fcber erfahren m\u00f6chten, wie wir die Karrieren unserer Mitarbeiter f\u00f6rdern, klicken Sie bitte auf die Schaltfl\u00e4che unten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0baf19 elementor-widget elementor-widget-button\" data-id=\"c0baf19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/wp-content\/uploads\/2025\/01\/SH-Careers-Brochure-25.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\"><path d=\"M14.8172 7.44205L9.19219 13.067C9.07491 13.1843 8.91585 13.2502 8.75 13.2502C8.58415 13.2502 8.42509 13.1843 8.30781 13.067C8.19054 12.9498 8.12465 12.7907 8.12465 12.6249C8.12465 12.459 8.19054 12.2999 8.30781 12.1827L12.8664 7.62486H0.625C0.45924 7.62486 0.300269 7.55901 0.183058 7.4418C0.0658482 7.32459 0 7.16562 0 6.99986C0 6.8341 0.0658482 6.67513 0.183058 6.55792C0.300269 6.44071 0.45924 6.37486 0.625 6.37486H12.8664L8.30781 1.81705C8.19054 1.69977 8.12465 1.54071 8.12465 1.37486C8.12465 1.20901 8.19054 1.04995 8.30781 0.932672C8.42509 0.815396 8.58415 0.749512 8.75 0.749512C8.91585 0.749512 9.07491 0.815396 9.19219 0.932672L14.8172 6.55767C14.8753 6.61572 14.9214 6.68465 14.9529 6.76052C14.9843 6.8364 15.0005 6.91772 15.0005 6.99986C15.0005 7.08199 14.9843 7.16332 14.9529 7.2392C14.9214 7.31507 14.8753 7.384 14.8172 7.44205Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Sheffield Harworth Berufserfahrung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-868fe29 e-flex e-con-boxed e-con e-parent\" data-id=\"868fe29\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c41c704 e-con-full e-flex e-con e-child\" data-id=\"c41c704\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6f85da2 e-con-full e-flex e-con e-child\" data-id=\"6f85da2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78fe2e1 elementor-widget elementor-widget-image\" data-id=\"78fe2e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg\" class=\"attachment-large size-large wp-image-21892\" alt=\"\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg 1024w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-300x200.jpg 300w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-768x512.jpg 768w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1536x1024.jpg 1536w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-99e68be e-con-full e-flex e-con e-child\" data-id=\"99e68be\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b1916ca elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"b1916ca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Arbeiten bei Sheffield Haworth<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6376fec elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"6376fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00dcber das Tagesgesch\u00e4ft hinaus f\u00f6rdern wir das Gemeinschaftsgef\u00fchl durch regelm\u00e4\u00dfige Kundenveranstaltungen und Firmentreffen auf der ganzen Welt. Diese bieten die M\u00f6glichkeit, Beziehungen aufzubauen, Erkenntnisse auszutauschen und unsere Erfolge gemeinsam zu feiern. Ganz gleich, ob es sich um ein Networking-Event, eine Preisverleihung, eine Wohlt\u00e4tigkeitsveranstaltung oder einen geselligen Ausflug handelt, diese Momente tragen dazu bei, dass wir als Team zusammenhalten und aufeinander abgestimmt sind.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e804779 e-con-full e-flex e-con e-child\" data-id=\"e804779\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-12f10fd e-con-full e-flex e-con e-child\" data-id=\"12f10fd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e7b1c3 elementor-widget elementor-widget-spacer\" data-id=\"2e7b1c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f096c9a e-con-full e-flex e-con e-child\" data-id=\"f096c9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7d3e849 e-con-full e-flex e-con e-child\" data-id=\"7d3e849\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9dea56e e-con-full e-flex e-con e-child\" data-id=\"9dea56e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0257038 elementor-widget elementor-widget-image\" data-id=\"0257038\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"279\" height=\"289\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2024\/09\/Rectangle-2-1.png\" class=\"attachment-large size-large wp-image-21454\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c060054 e-con-full e-flex e-con e-child\" data-id=\"c060054\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e75292 elementor-widget elementor-widget-image\" data-id=\"2e75292\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"279\" height=\"289\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2024\/09\/Rectangle-3-1.png\" class=\"attachment-large size-large wp-image-21452\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bb34a80 e-con-full e-flex e-con e-child\" data-id=\"bb34a80\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6ba843 e-flex e-con-boxed e-con e-parent\" data-id=\"e6ba843\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-50d2037 e-con-full e-flex e-con e-child\" data-id=\"50d2037\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75e2538 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"75e2538\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zu unseren aktuellen Positionen in unseren weltweiten Niederlassungen geh\u00f6ren:<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c2a579c e-con-full e-flex e-con e-child\" data-id=\"c2a579c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c70361 elementor-widget__width-initial elementor-widget elementor-widget-shortcode\" data-id=\"7c70361\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t<div class=\"awsm-job-wrap\">\n\n\t\t<div class=\"awsm-filter-wrap awsm-no-search-filter-wrap\"><form action=\"https:\/\/www.sheffieldhaworth.com\/wp-admin\/admin-ajax.php\" method=\"POST\"><a href=\"#\" class=\"awsm-filter-toggle\" role=\"button\" aria-pressed=\"false\"><span class=\"awsm-filter-toggle-text-wrapper\">Filter by<\/span><svg width=\"100\" height=\"100\" viewBox=\"0 0 100 100\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" preserveAspectRatio=\"xMinYMin\"><path xmlns=\"http:\/\/www.w3.org\/2000\/svg\" fill=\"rgb(9.803922%,9.803922%,9.803922%)\" d=\"M 36.417969 19.9375 L 36.417969 17.265625 C 36.417969 16.160156 35.523438 15.265625 34.417969 15.265625 L 21.578125 15.265625 C 20.476562 15.265625 19.578125 16.160156 19.578125 17.265625 L 19.578125 19.9375 L 11 19.9375 L 11 26.9375 L 19.578125 26.9375 L 19.578125 30.105469 C 19.578125 31.210938 20.476562 32.105469 21.578125 32.105469 L 34.417969 32.105469 C 35.523438 32.105469 36.417969 31.210938 36.417969 30.105469 L 36.417969 26.9375 L 89 26.9375 L 89 19.9375 Z M 58.421875 43.578125 C 58.421875 42.476562 57.527344 41.578125 56.421875 41.578125 L 43.582031 41.578125 C 42.480469 41.578125 41.582031 42.476562 41.582031 43.578125 L 41.582031 46.5 L 11 46.5 L 11 53.5 L 41.582031 53.5 L 41.582031 56.421875 C 41.582031 57.527344 42.480469 58.421875 43.582031 58.421875 L 56.421875 58.421875 C 57.527344 58.421875 58.421875 57.527344 58.421875 56.421875 L 58.421875 53.5 L 89 53.5 L 89 46.5 L 58.421875 46.5 Z M 80.417969 70.140625 C 80.417969 69.035156 79.523438 68.140625 78.417969 68.140625 L 65.578125 68.140625 C 64.476562 68.140625 63.578125 69.035156 63.578125 70.140625 L 63.578125 73.0625 L 11 73.0625 L 11 80.0625 L 63.578125 80.0625 L 63.578125 82.984375 C 63.578125 84.085938 64.476562 84.984375 65.578125 84.984375 L 78.417969 84.984375 C 79.523438 84.984375 80.417969 84.085938 80.417969 82.984375 L 80.417969 80.0625 L 89 80.0625 L 89 73.0625 L 80.417969 73.0625 Z M 80.417969 70.140625\"\/><\/svg><\/a><div class=\"awsm-filter-items\"><div class=\"awsm-filter-item\" data-filter=\"job__categories_spec\"><label for=\"awsm-job-categories-filter-option-1\" class=\"awsm-sr-only\">All Job Categories<\/label><select name=\"awsm_job_spec[job-categories]\" class=\"awsm-filter-option awsm-job-categories-filter-option\" id=\"awsm-job-categories-filter-option-1\" aria-label=\"All Job Categories\"><option value=\"\">All Job Categories<\/option><option value=\"234\" data-slug=\"associate-global-banking\">Associate-Global Banking<\/option><option value=\"233\" data-slug=\"graduate-associate\">Graduate Associate<\/option><option value=\"494\" data-slug=\"associate\">Associate<\/option><\/select><\/div><\/div><input type=\"hidden\" name=\"lang\" value=\"de\"><input type=\"hidden\" name=\"awsm_pagination_base\" value=\"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/pages\/21446\/\"><input type=\"hidden\" name=\"paged\" value=\"1\"><input type=\"hidden\" name=\"action\" value=\"jobfilter\"><\/form><\/div>\n\t\t<div class=\"awsm-job-listings awsm-lists\" data-listings=\"10\" data-lang=\"de\">\n\t\t\t\t\t<div class=\"awsm-job-listing-item awsm-list-item\" id=\"awsm-list-item-21350\">\t\t<div class=\"awsm-job-item\">\t\t\t<div class=\"awsm-list-left-col\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h2 class=\"awsm-job-post-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.sheffieldhaworth.com\/de\/jobs\/associate-global-banking\/\">Associate-Global Banking<\/a>\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"awsm-list-right-col\">\n\t\t\t\t<div class=\"awsm-job-specification-wrapper\"><div class=\"awsm-job-specification-item awsm-job-specification-job-location\"><span class=\"awsm-job-specification-term\">NewYork<\/span> <\/div><\/div><div class=\"awsm-job-more-container\"><a class=\"awsm-job-more\" href=\"https:\/\/www.sheffieldhaworth.com\/de\/jobs\/associate-global-banking\/\">More Details <span><\/span><\/a><\/div>\t\t\t<\/div>\n\t\t<\/div>\t<\/div><div class=\"awsm-job-listing-item awsm-list-item\" id=\"awsm-list-item-21352\">\t\t<div class=\"awsm-job-item\">\t\t\t<div class=\"awsm-list-left-col\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<h2 class=\"awsm-job-post-title\">\n\t\t\t\t\t<a href=\"https:\/\/www.sheffieldhaworth.com\/de\/jobs\/diplomierter-associate\/\">Diplomierter Associate<\/a>\t\t\t\t<\/h2>\n\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t<div class=\"awsm-list-right-col\">\n\t\t\t\t<div class=\"awsm-job-specification-wrapper\"><div class=\"awsm-job-specification-item awsm-job-specification-job-location\"><span class=\"awsm-job-specification-term\">London<\/span> <\/div><\/div><div class=\"awsm-job-more-container\"><a class=\"awsm-job-more\" href=\"https:\/\/www.sheffieldhaworth.com\/de\/jobs\/diplomierter-associate\/\">More Details <span><\/span><\/a><\/div>\t\t\t<\/div>\n\t\t<\/div>\t<\/div>\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fc1fb51 e-flex e-con-boxed e-con e-parent\" data-id=\"fc1fb51\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65b1f3a e-con-full e-flex e-con e-child\" data-id=\"65b1f3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-355eb55 elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"355eb55\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unser Einfluss<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26c87ee elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"26c87ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei Sheffield Haworth liegt uns nicht nur der Einfluss auf die Organisationen und Menschen am Herzen, mit denen wir zusammenarbeiten, sondern auch das Verm\u00e4chtnis, das wir im Bereich Umwelt, Soziales und Unternehmensf\u00fchrung (ESG) hinterlassen.  <\/p><p><br>Wir sind daf\u00fcr verantwortlich, dass wir bei allem, was wir tun, Inklusion und Vielfalt sowie eine gute Unternehmensf\u00fchrung f\u00f6rdern und unsere Umweltauswirkungen minimieren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-966c316 elementor-widget elementor-widget-button\" data-id=\"966c316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.sheffieldhaworth.com\/de\/auswirkungen\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"15\" height=\"14\" viewBox=\"0 0 15 14\" fill=\"none\"><path d=\"M14.8172 7.44205L9.19219 13.067C9.07491 13.1843 8.91585 13.2502 8.75 13.2502C8.58415 13.2502 8.42509 13.1843 8.30781 13.067C8.19054 12.9498 8.12465 12.7907 8.12465 12.6249C8.12465 12.459 8.19054 12.2999 8.30781 12.1827L12.8664 7.62486H0.625C0.45924 7.62486 0.300269 7.55901 0.183058 7.4418C0.0658482 7.32459 0 7.16562 0 6.99986C0 6.8341 0.0658482 6.67513 0.183058 6.55792C0.300269 6.44071 0.45924 6.37486 0.625 6.37486H12.8664L8.30781 1.81705C8.19054 1.69977 8.12465 1.54071 8.12465 1.37486C8.12465 1.20901 8.19054 1.04995 8.30781 0.932672C8.42509 0.815396 8.58415 0.749512 8.75 0.749512C8.91585 0.749512 9.07491 0.815396 9.19219 0.932672L14.8172 6.55767C14.8753 6.61572 14.9214 6.68465 14.9529 6.76052C14.9843 6.8364 15.0005 6.91772 15.0005 6.99986C15.0005 7.08199 14.9843 7.16332 14.9529 7.2392C14.9214 7.31507 14.8753 7.384 14.8172 7.44205Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Finden Sie mehr heraus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a6a4e8 e-flex e-con-boxed e-con e-parent\" data-id=\"1a6a4e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-daa3ae7 e-con-full e-flex e-con e-child\" data-id=\"daa3ae7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c4f0ea0 elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"c4f0ea0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Was sagen unsere Mitarbeiter?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c27516 e-con-full e-flex e-con e-child\" data-id=\"6c27516\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-789829d elementor-pagination-type-bullets elementor-arrows-position-inside elementor-pagination-position-outside elementor-widget elementor-widget-n-carousel\" data-id=\"789829d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;carousel_items&quot;:[{&quot;slide_title&quot;:&quot;Andrew&quot;,&quot;_id&quot;:&quot;89439e2&quot;},{&quot;slide_title&quot;:&quot;Jannah&quot;,&quot;_id&quot;:&quot;1f400d1&quot;},{&quot;slide_title&quot;:&quot;Jennie Frewen&quot;,&quot;_id&quot;:&quot;870c419&quot;},{&quot;slide_title&quot;:&quot;Ben Tilley&quot;,&quot;_id&quot;:&quot;7d509b4&quot;},{&quot;slide_title&quot;:&quot;Adam Dunn&quot;,&quot;_id&quot;:&quot;7c3e0bb&quot;}],&quot;slides_to_show&quot;:&quot;1&quot;,&quot;slides_to_show_tablet&quot;:&quot;2&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;offset_sides&quot;:&quot;none&quot;,&quot;arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-carousel swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"1\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ea4cc0 e-flex e-con-boxed e-con e-child\" data-id=\"4ea4cc0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2156b95 e-con-full e-flex e-con e-child\" data-id=\"2156b95\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d644f97 elementor-widget elementor-widget-image\" data-id=\"d644f97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"557\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/06\/Andrew-Thomposn.png\" class=\"attachment-large size-large wp-image-7659\" alt=\"Andrew Thompson\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/06\/Andrew-Thomposn.png 575w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/06\/Andrew-Thomposn-300x291.png 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c8ae327 e-con-full e-flex e-con e-child\" data-id=\"c8ae327\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c63a2e elementor-widget elementor-widget-text-editor\" data-id=\"6c63a2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sheffield Haworth hat einen sehr unternehmerischen Geist und bietet Menschen in jedem Alter und in jeder Phase ihrer Karriere echte Chancen. Das Einzigartige an dem Unternehmen ist der Zugang, den man als Associate zu den leitenden Angestellten des Unternehmens erh\u00e4lt, die mehr als bereit sind, ihr Wissen und ihre Erfahrungen mit Ihnen zu teilen &#8211; etwas, das man in einer gr\u00f6\u00dferen Firma nicht bekommt.&#8220; <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae4a601 elementor-widget elementor-widget-heading\" data-id=\"ae4a601\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Andrew Thompson<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e161d84 elementor-widget elementor-widget-text-editor\" data-id=\"e161d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gesch\u00e4ftsf\u00fchrer, Praxis f\u00fcr Verm\u00f6gensverwaltung, New York<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"2\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe636e8 e-flex e-con-boxed e-con e-child\" data-id=\"fe636e8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c6248f7 e-con-full e-flex e-con e-child\" data-id=\"c6248f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-34280c4 elementor-widget elementor-widget-image\" data-id=\"34280c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"571\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/07\/Jannah-Babasa.png\" class=\"attachment-large size-large wp-image-8636\" alt=\"\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/07\/Jannah-Babasa.png 571w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/07\/Jannah-Babasa-300x300.png 300w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/07\/Jannah-Babasa-150x150.png 150w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4295db8 e-con-full e-flex e-con e-child\" data-id=\"4295db8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12b11b8 elementor-widget elementor-widget-text-editor\" data-id=\"12b11b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8222;Ich genie\u00dfe die enge Zusammenarbeit mit meinen Managern und anderen leitenden Angestellten, die das Lernen und die Entwicklung in Echtzeit sowie das Mentoring f\u00f6rdert. Ich habe das Gl\u00fcck, mit gro\u00dfartigen Menschen zusammenzuarbeiten, die klug, motiviert und engagiert sind, was zu einer starken internen Kultur beitr\u00e4gt. Die Firma ist au\u00dferdem unternehmerisch und leistungsorientiert, mit klaren Rahmenbedingungen f\u00fcr die Karriereentwicklung, aber ohne zu viel Starrheit. Jeder wird ermutigt, so viel Verantwortung zu \u00fcbernehmen, wie er sich wohl f\u00fchlt, und sein Erfolg wird gefeiert und belohnt.&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-493ab0c elementor-widget elementor-widget-heading\" data-id=\"493ab0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jannah Babasa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d91fa1 elementor-widget elementor-widget-text-editor\" data-id=\"6d91fa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Berater, Immobilienpraxis, New York<\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"3\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b04c424 e-flex e-con-boxed e-con e-child\" data-id=\"b04c424\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7ae35db e-con-full e-flex e-con e-child\" data-id=\"7ae35db\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c441ba1 elementor-widget elementor-widget-image\" data-id=\"c441ba1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"571\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Jennie_Frewen.png\" class=\"attachment-large size-large wp-image-8576\" alt=\"\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Jennie_Frewen.png 571w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Jennie_Frewen-300x300.png 300w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Jennie_Frewen-150x150.png 150w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be38180 e-con-full e-flex e-con e-child\" data-id=\"be38180\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbdd3f8 elementor-widget elementor-widget-text-editor\" data-id=\"bbdd3f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>&#8222;Ich kam 2013 als Praktikantin im Londoner B\u00fcro zu dem Unternehmen, das urspr\u00fcnglich nbi consulting hie\u00df und sp\u00e4ter von Sheffield Haworth \u00fcbernommen wurde. Seitdem hatte ich die Gelegenheit, in Hongkong, Singapur und zuletzt in Dubai zu arbeiten. Was ich an meiner Arbeit am meisten liebe, ist die M\u00f6glichkeit, mit gro\u00dfartigen Kollegen in verschiedenen L\u00e4ndern zusammenzuarbeiten und Spa\u00df daran zu haben, f\u00fcr unsere Kunden wirklich etwas zu bewirken. Ich genie\u00dfe es sehr, Teil des Wachstums der Beratungs- und Professional Services-Praxis zu sein, unsere Gro\u00dfkunden in verschiedenen L\u00e4ndern zu vergr\u00f6\u00dfern und zu sehen, welche positiven Auswirkungen unsere Arbeit auf unsere Kunden hat.&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b359156 elementor-widget elementor-widget-heading\" data-id=\"b359156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jennie Frewen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5feffca elementor-widget elementor-widget-text-editor\" data-id=\"5feffca\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Direktor, Beratung und professionelle Dienstleistungen, Dubai<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"4\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-606296c e-flex e-con-boxed e-con e-child\" data-id=\"606296c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e3746bf e-con-full e-flex e-con e-child\" data-id=\"e3746bf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96f02c2 elementor-widget elementor-widget-image\" data-id=\"96f02c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"569\" height=\"579\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/05\/Ben-Tilley.png\" class=\"attachment-large size-large wp-image-7581\" alt=\"Benjamin Tilley\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/05\/Ben-Tilley.png 569w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/05\/Ben-Tilley-295x300.png 295w\" sizes=\"(max-width: 569px) 100vw, 569px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d88fd15 e-con-full e-flex e-con e-child\" data-id=\"d88fd15\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03dd429 elementor-widget elementor-widget-text-editor\" data-id=\"03dd429\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><br>&#8222;Schon in den ersten Wochen nach meinem Eintritt in das Unternehmen habe ich Kunden- und Kandidatengespr\u00e4che gef\u00fchrt und an einer faszinierenden SpaceTech-Konferenz teilgenommen. Ich habe mehr Verantwortung bei Kundengespr\u00e4chen \u00fcbernommen und bin jetzt der alleinige Rechercheur bei Suchen in Zusammenarbeit mit einem Berater. Dieser klare Weg der Weiterentwicklung war einer der Gr\u00fcnde, warum ich mich f\u00fcr das Unternehmen entschieden habe.&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98feb88 elementor-widget elementor-widget-heading\" data-id=\"98feb88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ben Tilley<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bffb944 elementor-widget elementor-widget-text-editor\" data-id=\"bffb944\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Senior Associate, Technologie-Praxis, London<\/p><p> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" data-slide=\"5\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fd6022d e-flex e-con-boxed e-con e-child\" data-id=\"fd6022d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9dd0171 e-con-full e-flex e-con e-child\" data-id=\"9dd0171\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58b7b47 elementor-widget elementor-widget-image\" data-id=\"58b7b47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"571\" height=\"571\" src=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Adam-Dunn.png\" class=\"attachment-large size-large wp-image-8564\" alt=\"Adam-Dunn\" srcset=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Adam-Dunn.png 571w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Adam-Dunn-300x300.png 300w, https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2022\/09\/Adam-Dunn-150x150.png 150w\" sizes=\"(max-width: 571px) 100vw, 571px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52f1272 e-con-full e-flex e-con e-child\" data-id=\"52f1272\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c40eff9 elementor-widget elementor-widget-text-editor\" data-id=\"c40eff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><br>&#8222;Sheffield Haworth hat mir das Selbstvertrauen gegeben, in gr\u00f6\u00dferen Dimensionen zu denken und in der Lage zu sein, Arbeit in gro\u00dfem Ma\u00dfstab zu verkaufen und zu liefern. Ich habe auch gelernt, mit anderen im Team und im gesamten Unternehmen zusammenzuarbeiten.&#8220;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b17cfc4 elementor-widget elementor-widget-heading\" data-id=\"b17cfc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Adam Dunn<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb40f13 elementor-widget elementor-widget-text-editor\" data-id=\"eb40f13\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gesch\u00e4ftsf\u00fchrender Direktor, Professionelle Dienstleistungen, London<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Voriger\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"N\u00e4chster\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewBox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-255761e e-flex e-con-boxed e-con e-parent\" data-id=\"255761e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b4b9bdd e-con-full e-flex e-con e-child\" data-id=\"b4b9bdd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-af2c3f6 e-con-full e-flex e-con e-child\" data-id=\"af2c3f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4203a2b elementor-widget elementor-widget-heading\" data-id=\"4203a2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Behinderung Zuversichtlicher Engagierter Arbeitgeber<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eee6680 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eee6680\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind stolz darauf, den Status &#8222;disability confident level 2 committed&#8220; erreicht zu haben und setzen uns daf\u00fcr ein, dass Menschen mit Behinderungen und Langzeiterkrankungen die M\u00f6glichkeit haben, ihr Potenzial auszusch\u00f6pfen und ihre W\u00fcnsche zu verwirklichen.<\/p><p>Als Disability Confident Committed Employer verpflichten wir uns zu:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b121003 e-con-full e-flex e-con e-child\" data-id=\"b121003\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-175b849 e-con-full e-flex e-con e-child\" data-id=\"175b849\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b5999c2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b5999c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sicherstellen, dass unser Rekrutierungsprozess inklusiv und zug\u00e4nglich ist<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a1d00c0 e-con-full e-flex e-con e-child\" data-id=\"a1d00c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d4e5eb elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4d4e5eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Freie Stellen kommunizieren und bewerben<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf31544 e-con-full e-flex e-con e-child\" data-id=\"cf31544\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-05beab0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"05beab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Angebot eines Vorstellungsgespr\u00e4chs f\u00fcr behinderte Menschen, die die Mindestkriterien f\u00fcr die Stelle erf\u00fcllen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9e7e5ca e-con-full e-flex e-con e-child\" data-id=\"9e7e5ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d410fc elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7d410fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Antizipation und Bereitstellung angemessener Anpassungen, falls erforderlich<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6c5bc91 e-con-full e-flex e-con e-child\" data-id=\"6c5bc91\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e62b85 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"3e62b85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unterst\u00fctzung von Arbeitnehmern, die eine Behinderung oder einen langfristigen Gesundheitszustand erleiden, um ihnen den Verbleib im Beruf zu erm\u00f6glichen<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f36c67 e-con-full e-flex e-con e-child\" data-id=\"6f36c67\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c478c32 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c478c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mindestens eine Aktivit\u00e4t, die f\u00fcr behinderte Menschen einen Unterschied macht<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fffa32a elementor-widget elementor-widget-button\" data-id=\"fffa32a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/disabilityconfident.campaign.gov.uk\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"20\" viewBox=\"0 0 20 20\" fill=\"none\"><path d=\"M17.3172 10.442L11.6922 16.067C11.5749 16.1843 11.4159 16.2502 11.25 16.2502C11.0841 16.2502 10.9251 16.1843 10.8078 16.067C10.6905 15.9498 10.6247 15.7907 10.6247 15.6249C10.6247 15.459 10.6905 15.2999 10.8078 15.1827L15.3664 10.6249H3.125C2.95924 10.6249 2.80027 10.559 2.68306 10.4418C2.56585 10.3246 2.5 10.1656 2.5 9.99986C2.5 9.8341 2.56585 9.67513 2.68306 9.55792C2.80027 9.44071 2.95924 9.37486 3.125 9.37486H15.3664L10.8078 4.81705C10.6905 4.69977 10.6247 4.54071 10.6247 4.37486C10.6247 4.20901 10.6905 4.04995 10.8078 3.93267C10.9251 3.8154 11.0841 3.74951 11.25 3.74951C11.4159 3.74951 11.5749 3.8154 11.6922 3.93267L17.3172 9.55767C17.3753 9.61572 17.4214 9.68465 17.4529 9.76052C17.4843 9.8364 17.5005 9.91772 17.5005 9.99986C17.5005 10.082 17.4843 10.1633 17.4529 10.2392C17.4214 10.3151 17.3753 10.384 17.3172 10.442Z\" fill=\"#252D71\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Finden Sie mehr heraus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Karriere Karriere bei Sheffield Haworth Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt Um unseren Kunden die besten L\u00f6sungen anbieten zu k\u00f6nnen, m\u00fcssen wir die besten Talente einstellen. Die sich schnell entwickelnde Wirtschaft von heute ist auf Talente angewiesen. Die richtigen F\u00e4higkeiten und die richtigen Mitarbeiter sind der Motor [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-21446","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Karriere - Sheffield Haworth<\/title>\n<meta name=\"description\" content=\"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karriere - Sheffield Haworth\" \/>\n<meta property=\"og:description\" content=\"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/\" \/>\n<meta property=\"og:site_name\" content=\"Sheffield Haworth\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-26T16:12:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/\",\"name\":\"Karriere - Sheffield Haworth\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/win-party-NYC-2-1024x683.jpg\",\"datePublished\":\"2024-09-04T20:53:38+00:00\",\"dateModified\":\"2025-08-26T16:12:13+00:00\",\"description\":\"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/karriere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/win-party-NYC-2-1024x683.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/win-party-NYC-2-1024x683.jpg\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/\",\"name\":\"Sheffield Haworth\",\"description\":\"Organisationen und Einzelpersonen dabei helfen, ihr Potenzial auszusch\u00f6pfen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#organization\",\"name\":\"Sheffield Haworth\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"contentUrl\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/mstile-310x150-1.png\",\"width\":311,\"height\":151,\"caption\":\"Sheffield Haworth\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sheffieldhaworth.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/sheffield-haworth\\\/?viewAsMember=true\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Karriere - Sheffield Haworth","description":"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/","og_locale":"de_DE","og_type":"article","og_title":"Karriere - Sheffield Haworth","og_description":"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.","og_url":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/","og_site_name":"Sheffield Haworth","article_modified_time":"2025-08-26T16:12:13+00:00","og_image":[{"url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/","url":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/","name":"Karriere - Sheffield Haworth","isPartOf":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/#primaryimage"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg","datePublished":"2024-09-04T20:53:38+00:00","dateModified":"2025-08-26T16:12:13+00:00","description":"Erreichen Sie Ihr volles Potenzial in einer der dynamischsten und aufregendsten Branchen der Welt und werden Sie Teil eines wirklich globalen Teams.","inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sheffieldhaworth.com\/de\/karriere\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sheffieldhaworth.com\/de\/karriere\/#primaryimage","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2025\/04\/win-party-NYC-2-1024x683.jpg"},{"@type":"WebSite","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#website","url":"https:\/\/www.sheffieldhaworth.com\/de\/","name":"Sheffield Haworth","description":"Organisationen und Einzelpersonen dabei helfen, ihr Potenzial auszusch\u00f6pfen","publisher":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sheffieldhaworth.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#organization","name":"Sheffield Haworth","url":"https:\/\/www.sheffieldhaworth.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","contentUrl":"https:\/\/www.sheffieldhaworth.com\/wp-content\/uploads\/2021\/10\/mstile-310x150-1.png","width":311,"height":151,"caption":"Sheffield Haworth"},"image":{"@id":"https:\/\/www.sheffieldhaworth.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/sheffield-haworth\/?viewAsMember=true"]}]}},"_links":{"self":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/pages\/21446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/comments?post=21446"}],"version-history":[{"count":0,"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/pages\/21446\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.sheffieldhaworth.com\/de\/wp-json\/wp\/v2\/media?parent=21446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}